{"id":38296,"date":"2024-11-01T12:31:00","date_gmt":"2024-11-01T11:31:00","guid":{"rendered":"https:\/\/museuart.cat\/exposicions\/roser-moreno-superar-la-distancia\/"},"modified":"2026-05-11T11:23:12","modified_gmt":"2026-05-11T09:23:12","slug":"roser-moreno-superar-la-distancia","status":"publish","type":"exposicions","link":"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/","title":{"rendered":"Roser Bru . Superar la distancia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">La exposici\u00f3n est\u00e1 dedicada a la obra y figura de la artista catalana-chilena Roser Bru i Llop (Barcelona 1923 \u2013 Santiago de Chile 2021). Roser Bru naci\u00f3 en Barcelona y de peque\u00f1a vivi\u00f3 un primer exilio familiar en Par\u00eds, durante la dictadura de Primo de Rivera. Devueltos a Barcelona vivieron intensamente la proclamaci\u00f3n de la Rep\u00fablica y seguidamente un segundo y definitivo exilio que llevar\u00eda a la familia, primero a Francia y seguidamente a Chile, embarcados en el barco Winnipeg, alquilado por Pablo Neruda, quien entonces era c\u00f3nsul en Par\u00eds.  <\/p>\n\n<p class=\"wp-block-paragraph\">Roser Bru estudi\u00f3 Bellas Artes en Santiago y mantuvo una gran amistad con Neruda, as\u00ed como con otros exiliados catalanes, especialmente con la escritora Montserrat Abell\u00f3. De hecho, a pesar de desarrollar toda su carrera art\u00edstica en Chile, Bru siempre mantuvo vivas las ra\u00edces catalanas y los contactos con artistas y escritores catalanes. Su obra primera estuvo influenciada por las iconograf\u00edas del rom\u00e1nico catal\u00e1n, especialmente las figuras tot\u00e9micas de las v\u00edrgenes, y tambi\u00e9n una evidente influencia del informalismo catal\u00e1n, sobre todo de la obra de T\u00e0pies, que descubri\u00f3 en un primer viaje de regreso a Catalu\u00f1a en 1958.  <\/p>\n\n<p class=\"wp-block-paragraph\">Pintora y grabadora, se convirti\u00f3 en una de las artistas m\u00e1s destacadas y reconocidas en Chile, donde fue galardonada con el Premio Nacional de Artes Pl\u00e1sticas, en 2015. En 2018 recibi\u00f3 la Medalla de Oro en el M\u00e9rito de las Bellas Artes Espa\u00f1olas, como reconocimiento y homenaje a su figura. Cinco a\u00f1os m\u00e1s tarde recibi\u00f3 la Cruz de San Jorge de la Generalidad de Catalu\u00f1a.  <\/p>\n\n<p class=\"wp-block-paragraph\">Bruno muri\u00f3 con 98 a\u00f1os en el 2021. Justo el a\u00f1o pasado se celebr\u00f3 en Chile en centenario de su nacimiento, que se hace extensivo ahora con la exposici\u00f3n del Museo de Arte de Girona. <\/p>\n\n<p class=\"wp-block-paragraph\">La exposici\u00f3n del Museo de Arte de Girona, titulada \u00abRoser Bru. Superar la distancia\u00bb permite volver a ver obra de Bru en Catalunya despu\u00e9s de casi 20 a\u00f1os. La muestra, co-comisariada por \u00c0lex Mitrani e In\u00e9s Ortega-M\u00e1rquez, quiere poner de relieve el origen catal\u00e1n de Roser Bru, as\u00ed como el v\u00ednculo emocional, pero tambi\u00e9n art\u00edstico, que mantuvo con Catalunya. Asimismo, quiere recuperar su figura y trayectoria, cuya propuesta se desarrolla a partir de tres ejes tem\u00e1ticos -las iconograf\u00edas femeninas, las reivindicaciones democr\u00e1ticas y los referentes human\u00edsticos y geogr\u00e1ficos- y que busca mostrar la dimensi\u00f3n de la obra de Roser Bru y hacerla presente, de nuevo, en Catalu\u00f1a.  <\/p>\n\n<p class=\"wp-block-paragraph\">El proyecto expositivo se desarrolla y ha recibido el impulso y apoyo de la embajada de Chile en Espa\u00f1a y del Ministerio de Cultura de Chile, y la colaboraci\u00f3n de la Fundaci\u00f3n Roser Bru en Chile, as\u00ed como un apoyo especial del Departamento de Cultura de la Generalidad de Catalu\u00f1a, y el acompa\u00f1amiento del Institut Ramon Llull y de la Casa Am\u00e8rica Catalunya, entre otros.<\/p>\n\n<p class=\"wp-block-paragraph\">La exposici\u00f3n concentra y presenta en Gerona un importante volumen de obras y grabados del artista, as\u00ed como documentos y objetos, la mayor\u00eda procedentes de Chile. En total, 30 obras pict\u00f3ricas y 40 grabados de formatos diversos, la mayor\u00eda propiedad de la Fundaci\u00f3n Roser Bru de Chile, pero tambi\u00e9n pr\u00e9stamos de obras destacadas de museos y de colecciones privadas chilenas. \u00c9stas se presentan conjuntamente con cerca de 25 pinturas, grabados y documentos procedentes de museos nacionales, como el Museo Nacional Reina Sof\u00eda de Madrid, el Museo Nacional de Arte de Catalu\u00f1a, la Biblioteca de Catalu\u00f1a y de diversas colecciones privadas catalanas, que ponen de manifiesto el v\u00ednculo permanente de Bru con su tierra natal.    <\/p>\n\n<p class=\"wp-block-paragraph\">En total, la exposici\u00f3n re\u00fane cerca de un centenar de obras, grabados y documentos de Roser Bru, y seguro ser\u00e1 una de las exposiciones m\u00e1s destacadas de la temporada.<\/p>\n","protected":false},"featured_media":38318,"template":"","estat-exposicions":[303],"class_list":["post-38296","exposicions","type-exposicions","status-publish","has-post-thumbnail","hentry","estat-exposicions-pasadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roser Bru . Superar la distancia - Museu d&#039;Art de Girona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roser Bru . Superar la distancia - Museu d&#039;Art de Girona\" \/>\n<meta property=\"og:description\" content=\"La exposici\u00f3n est\u00e1 dedicada a la obra y figura de la artista catalana-chilena Roser Bru i Llop (Barcelona 1923 \u2013 Santiago de Chile 2021). Roser Bru naci\u00f3 en Barcelona y de peque\u00f1a vivi\u00f3 un primer exilio familiar en Par\u00eds, durante la dictadura de Primo de Rivera. Devueltos a Barcelona vivieron intensamente la proclamaci\u00f3n de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/\" \/>\n<meta property=\"og:site_name\" content=\"Museu d&#039;Art de Girona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/museuartgirona\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T09:23:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/museuart.cat\/wp-content\/uploads\/2025\/12\/202411_RoserBru_web_portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MuseuArtGirona\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/exposicions\\\/roser-moreno-superar-la-distancia\\\/\",\"url\":\"https:\\\/\\\/museuart.cat\\\/es\\\/exposicions\\\/roser-moreno-superar-la-distancia\\\/\",\"name\":\"Roser Bru . Superar la distancia - Museu d&#039;Art de Girona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/exposicions\\\/roser-moreno-superar-la-distancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/exposicions\\\/roser-moreno-superar-la-distancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museuart.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/202411_RoserBru_web_portada.jpg\",\"datePublished\":\"2024-11-01T11:31:00+00:00\",\"dateModified\":\"2026-05-11T09:23:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/exposicions\\\/roser-moreno-superar-la-distancia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/museuart.cat\\\/es\\\/exposicions\\\/roser-moreno-superar-la-distancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/exposicions\\\/roser-moreno-superar-la-distancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/museuart.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/202411_RoserBru_web_portada.jpg\",\"contentUrl\":\"https:\\\/\\\/museuart.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/202411_RoserBru_web_portada.jpg\",\"width\":1600,\"height\":900,\"caption\":\"Roser Bru, Sense t\u00edtol, 1968. Fundaci\u00f3 Roser Bru, Xile. \u00a9 Roser Bru, VEGAP, Girona, 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/exposicions\\\/roser-moreno-superar-la-distancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/museuart.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exposicions\",\"item\":\"https:\\\/\\\/museuart.cat\\\/es\\\/exposicions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Roser Bru . Superar la distancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/museuart.cat\\\/es\\\/\",\"name\":\"Museu Art de Girona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museuart.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/#organization\",\"name\":\"Museu Art de Girona\",\"url\":\"https:\\\/\\\/museuart.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/museuart.cat\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/marg-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/museuart.cat\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/marg-logo.jpg\",\"width\":305,\"height\":90,\"caption\":\"Museu Art de Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/museuart.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/museuartgirona\\\/\",\"https:\\\/\\\/x.com\\\/MuseuArtGirona\",\"https:\\\/\\\/www.instagram.com\\\/museuartgirona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/museuartgirona\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roser Bru . Superar la distancia - Museu d&#039;Art de Girona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/","og_locale":"es_ES","og_type":"article","og_title":"Roser Bru . Superar la distancia - Museu d&#039;Art de Girona","og_description":"La exposici\u00f3n est\u00e1 dedicada a la obra y figura de la artista catalana-chilena Roser Bru i Llop (Barcelona 1923 \u2013 Santiago de Chile 2021). Roser Bru naci\u00f3 en Barcelona y de peque\u00f1a vivi\u00f3 un primer exilio familiar en Par\u00eds, durante la dictadura de Primo de Rivera. Devueltos a Barcelona vivieron intensamente la proclamaci\u00f3n de la [&hellip;]","og_url":"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/","og_site_name":"Museu d&#039;Art de Girona","article_publisher":"https:\/\/www.facebook.com\/museuartgirona\/","article_modified_time":"2026-05-11T09:23:12+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/museuart.cat\/wp-content\/uploads\/2025\/12\/202411_RoserBru_web_portada.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MuseuArtGirona","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/","url":"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/","name":"Roser Bru . Superar la distancia - Museu d&#039;Art de Girona","isPartOf":{"@id":"https:\/\/museuart.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/#primaryimage"},"image":{"@id":"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/#primaryimage"},"thumbnailUrl":"https:\/\/museuart.cat\/wp-content\/uploads\/2025\/12\/202411_RoserBru_web_portada.jpg","datePublished":"2024-11-01T11:31:00+00:00","dateModified":"2026-05-11T09:23:12+00:00","breadcrumb":{"@id":"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/#primaryimage","url":"https:\/\/museuart.cat\/wp-content\/uploads\/2025\/12\/202411_RoserBru_web_portada.jpg","contentUrl":"https:\/\/museuart.cat\/wp-content\/uploads\/2025\/12\/202411_RoserBru_web_portada.jpg","width":1600,"height":900,"caption":"Roser Bru, Sense t\u00edtol, 1968. Fundaci\u00f3 Roser Bru, Xile. \u00a9 Roser Bru, VEGAP, Girona, 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/museuart.cat\/es\/exposicions\/roser-moreno-superar-la-distancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/museuart.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Exposicions","item":"https:\/\/museuart.cat\/es\/exposicions\/"},{"@type":"ListItem","position":3,"name":"Roser Bru . Superar la distancia"}]},{"@type":"WebSite","@id":"https:\/\/museuart.cat\/es\/#website","url":"https:\/\/museuart.cat\/es\/","name":"Museu Art de Girona","description":"","publisher":{"@id":"https:\/\/museuart.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museuart.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/museuart.cat\/es\/#organization","name":"Museu Art de Girona","url":"https:\/\/museuart.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/museuart.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/museuart.cat\/wp-content\/uploads\/2025\/07\/marg-logo.jpg","contentUrl":"https:\/\/museuart.cat\/wp-content\/uploads\/2025\/07\/marg-logo.jpg","width":305,"height":90,"caption":"Museu Art de Girona"},"image":{"@id":"https:\/\/museuart.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/museuartgirona\/","https:\/\/x.com\/MuseuArtGirona","https:\/\/www.instagram.com\/museuartgirona\/","https:\/\/www.youtube.com\/c\/museuartgirona"]}]}},"_links":{"self":[{"href":"https:\/\/museuart.cat\/es\/wp-json\/wp\/v2\/exposicions\/38296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museuart.cat\/es\/wp-json\/wp\/v2\/exposicions"}],"about":[{"href":"https:\/\/museuart.cat\/es\/wp-json\/wp\/v2\/types\/exposicions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/museuart.cat\/es\/wp-json\/wp\/v2\/media\/38318"}],"wp:attachment":[{"href":"https:\/\/museuart.cat\/es\/wp-json\/wp\/v2\/media?parent=38296"}],"wp:term":[{"taxonomy":"estat-exposicions","embeddable":true,"href":"https:\/\/museuart.cat\/es\/wp-json\/wp\/v2\/estat-exposicions?post=38296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}